{"id":13834,"count":2,"description":"","link":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/","name":"#military technologies","slug":"military-technologies","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhive #military technologies - DISINFO.MD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/disinfo.md\/en\/tag\/military-technologies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive #military technologies - DISINFO.MD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/disinfo.md\/en\/tag\/military-technologies\/\" \/>\n<meta property=\"og:site_name\" content=\"DISINFO.MD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/disinfo.md\\\/en\\\/tag\\\/military-technologies\\\/\",\"url\":\"https:\\\/\\\/disinfo.md\\\/en\\\/tag\\\/military-technologies\\\/\",\"name\":\"Arhive #military technologies - DISINFO.MD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/disinfo.md\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/disinfo.md\\\/en\\\/tag\\\/military-technologies\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/disinfo.md\\\/en\\\/tag\\\/military-technologies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/disinfo.md\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#military technologies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/disinfo.md\\\/#website\",\"url\":\"https:\\\/\\\/disinfo.md\\\/\",\"name\":\"DISINFO.MD monitorizeaz\u0103 propaganda, dezinformarea \u0219i \u0219tirile false din Republica Moldova\",\"description\":\"monitoriz\u0103m propaganda \u0219i dezinformarea Now\",\"publisher\":{\"@id\":\"https:\\\/\\\/disinfo.md\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/disinfo.md\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/disinfo.md\\\/#organization\",\"name\":\"DISINFO.MD\",\"url\":\"https:\\\/\\\/disinfo.md\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/disinfo.md\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/disinfo.md\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-disinfo-new-alb-2.png\",\"contentUrl\":\"https:\\\/\\\/disinfo.md\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/logo-disinfo-new-alb-2.png\",\"width\":499,\"height\":151,\"caption\":\"DISINFO.MD\"},\"image\":{\"@id\":\"https:\\\/\\\/disinfo.md\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive #military technologies - DISINFO.MD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/","og_locale":"en_US","og_type":"article","og_title":"Arhive #military technologies - DISINFO.MD","og_url":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/","og_site_name":"DISINFO.MD","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/","url":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/","name":"Arhive #military technologies - DISINFO.MD","isPartOf":{"@id":"https:\/\/disinfo.md\/#website"},"breadcrumb":{"@id":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/disinfo.md\/en\/tag\/military-technologies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/disinfo.md\/en\/"},{"@type":"ListItem","position":2,"name":"#military technologies"}]},{"@type":"WebSite","@id":"https:\/\/disinfo.md\/#website","url":"https:\/\/disinfo.md\/","name":"DISINFO.MD monitorizeaz\u0103 propaganda, dezinformarea \u0219i \u0219tirile false din Republica Moldova","description":"monitoriz\u0103m propaganda \u0219i dezinformarea Now","publisher":{"@id":"https:\/\/disinfo.md\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/disinfo.md\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/disinfo.md\/#organization","name":"DISINFO.MD","url":"https:\/\/disinfo.md\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/disinfo.md\/#\/schema\/logo\/image\/","url":"https:\/\/disinfo.md\/wp-content\/uploads\/2025\/02\/logo-disinfo-new-alb-2.png","contentUrl":"https:\/\/disinfo.md\/wp-content\/uploads\/2025\/02\/logo-disinfo-new-alb-2.png","width":499,"height":151,"caption":"DISINFO.MD"},"image":{"@id":"https:\/\/disinfo.md\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/disinfo.md\/en\/wp-json\/wp\/v2\/tags\/13834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/disinfo.md\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/disinfo.md\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/disinfo.md\/en\/wp-json\/wp\/v2\/posts?tags=13834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}